{"id":6587,"date":"2024-05-24T08:27:09","date_gmt":"2024-05-24T11:27:09","guid":{"rendered":"https:\/\/alvopesquisa.com.br\/blogbelem\/?p=6587"},"modified":"2024-05-24T08:27:09","modified_gmt":"2024-05-24T11:27:09","slug":"tecnico-do-remo-saiu-do-corinthians-por-ir-a-atos-golpistas","status":"publish","type":"post","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/tecnico-do-remo-saiu-do-corinthians-por-ir-a-atos-golpistas\/","title":{"rendered":"T\u00e9cnico do Remo saiu do Corinthians por ir a atos golpistas"},"content":{"rendered":"<h4>Coluna do Gerson Nogueira\/DOL<\/h4>\n<h5>sexta-feira, 24\/05\/2024, 07:5<\/h5>\n<p>Sob fortes cr\u00edticas da torcida, a diretoria do Remo anunciou nesta quinta-feira a contrata\u00e7\u00e3o do t\u00e9cnico Rodrigo Santana para dirigir o time na S\u00e9rie C. Natural de Santos (SP), ele tem 41 anos e uma carreira que at\u00e9 hoje n\u00e3o decolou. Treinou Uberaba, URT, Atl\u00e9tico Mineiro, Ava\u00ed, Confian\u00e7a, Vaca Diez (Bol\u00edvia), Coritiba e Athletic, de onde foi demitido ap\u00f3s nove partidas. Ele vai se integrar \u00e0 delega\u00e7\u00e3o no Recife, onde o Remo joga s\u00e1bado contra o N\u00e1utico.<\/p>\n<p>Santana teve uma passagem curta e conturbada pelo Corinthians, em 2022, sendo demitido antes mesmo de assumir por press\u00e3o da torcida, ap\u00f3s ser fotografado nos acampamentos em frente aos quarteis.<\/p>\n<p>Bolsonarista assumido, ele havia participado das manifesta\u00e7\u00f5es golpistas realizadas ap\u00f3s a elei\u00e7\u00e3o de 2022 e a diretoria viu-se obrigada a dispens\u00e1-lo.<\/p>\n<p>No Corinthians, ele seria contratado como auxiliar t\u00e9cnico de Fernando L\u00e1zaro.<\/p>\n<p>Nas redes sociais, a torcida do Le\u00e3o se manifestou contra a contrata\u00e7\u00e3o. \u201cRodrigo Santana foi dispensado do Corinthians por participa\u00e7\u00e3o em atos golpistas. Atentar contra a democracia e o Estado Democr\u00e1tico de Direito n\u00e3o \u00e9 liberdade de opini\u00e3o: \u00e9 crime! O Remo n\u00e3o pode compactuar com este tipo de profissional. Golpista no Le\u00e3o, n\u00e3o!\u201d, postou o grupo Remo Antifascista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna do Gerson Nogueira\/DOL sexta-feira, 24\/05\/2024, 07:5 Sob fortes cr\u00edticas da torcida, a diretoria do&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[327],"tags":[],"class_list":["post-6587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=760%2C430&ssl=1",760,430,false],"thumbnail":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=300%2C170&ssl=1",300,170,true],"medium_large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=640%2C362&ssl=1",640,362,true],"large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=640%2C362&ssl=1",640,362,true],"1536x1536":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=760%2C430&ssl=1",760,430,true],"2048x2048":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=760%2C430&ssl=1",760,430,true],"newsever-slider-full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?resize=760%2C430&ssl=1",760,430,true],"newsever-featured":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=760%2C430&ssl=1",760,430,true],"newsever-medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?resize=720%2C430&ssl=1",720,430,true],"jetpack-portfolio-admin-thumb":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?resize=50%2C50&ssl=1",50,50,true]},"author_info":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/alvopesquisa.com.br\/blogbelem\/author\/socorro-borges\/"},"category_info":"<a href=\"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/\" rel=\"category tag\">Futebol<\/a>","tag_info":"Futebol","comment_count":"0","jetpack_featured_media_url":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/FOTO_00860922_0_-3.webp?fit=760%2C430&ssl=1","jetpack-related-posts":[{"id":8398,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/daniel-paulista-ex-crb-e-o-novo-tecnico-do-clube-do-remo\/","url_meta":{"origin":6587,"position":0},"title":"Daniel Paulista, ex-CRB, \u00e9 o novo t\u00e9cnico do Clube do Remo","author":"Reda\u00e7\u00e3o","date":"13 de mar\u00e7o de 2025","format":false,"excerpt":"Le\u00e3o j\u00e1 est\u00e1 nas \u00faltimas negocia\u00e7\u00f5es com o sucessor de Rodrigo Santana Autor:Andreia Santana\/Dol quinta-feira, 13\/03\/2025, 13:40 A p\u00f3s ter sido eliminado da Copa Verde e Copa do Brasil sob comando de Rodrigo Santana, o Clube do Remo demitiu o t\u00e9cnico na \u00faltima quarta-feira (12). Mas, sem perder tempo, o\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/imagemotimizada-1_00898038_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/imagemotimizada-1_00898038_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/imagemotimizada-1_00898038_0_-3.webp?fit=760%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/imagemotimizada-1_00898038_0_-3.webp?fit=760%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8385,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/primeira-crise\/","url_meta":{"origin":6587,"position":1},"title":"PRIMEIRA CRISE","author":"Reda\u00e7\u00e3o","date":"12 de mar\u00e7o de 2025","format":false,"excerpt":"Santana n\u00e3o resiste a mais uma elimina\u00e7\u00e3o e \u00e9 demitido do Remo Remo perde R$ 2,3 milh\u00f5es e demite t\u00e9cnico Rodrigo Santana ap\u00f3s queda na Copa do Brasil. Le\u00e3o ainda foi punido com perda de pontos no Paraz\u00e3o, nesta ter\u00e7a (11) Autor:Kaio Rodrigues\/Dol quarta-feira, 12\/03\/2025, 22:10 A elimina\u00e7\u00e3o na segunda\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/Rodrigo-Santana2_00862048_0_-3-1.webp?fit=760%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/Rodrigo-Santana2_00862048_0_-3-1.webp?fit=760%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/Rodrigo-Santana2_00862048_0_-3-1.webp?fit=760%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/Rodrigo-Santana2_00862048_0_-3-1.webp?fit=760%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10790,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/caiu-remo-demite-o-tecnico-portugues-antonio-oliveira\/","url_meta":{"origin":6587,"position":2},"title":"Caiu! Remo demite o t\u00e9cnico portugu\u00eas Ant\u00f3nio Oliveira","author":"Reda\u00e7\u00e3o","date":"21 de setembro de 2025","format":false,"excerpt":"Passagem do treinador chega ao fim ap\u00f3s a derrota para o Atl\u00e9tico-GO em pleno Baen\u00e3o Autor:Kaio Rodrigues\/Dol domingo, 21\/09\/2025, 14:55 A p\u00f3s uma extensa reuni\u00e3o na manh\u00e3 deste domingo (21), o executivo Marcos Braz e o t\u00e9cnico Ant\u00f3nio Oliveira chegaram a um acordo para o encerramento do v\u00ednculo do treinador\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/09\/Antonio-Oliveira3_00922278_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/09\/Antonio-Oliveira3_00922278_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/09\/Antonio-Oliveira3_00922278_0_-3.webp?fit=760%2C398&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/09\/Antonio-Oliveira3_00922278_0_-3.webp?fit=760%2C398&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7022,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/nao-competimos\/","url_meta":{"origin":6587,"position":3},"title":"Santana culpa &#8216;apag\u00e3o&#8217; e confus\u00e3o por derrota do Remo","author":"Reda\u00e7\u00e3o","date":"25 de junho de 2024","format":false,"excerpt":"Rodrigo Santana, treinador do Clube do Remo, critica falta de competitividade inicial e lamenta tumulto que atrapalhou rea\u00e7\u00e3o do time na derrota para o ABC por 3 a 1 na S\u00e9rie C. Autor:Sales Coimbra\/DOL ter\u00e7a-feira, 25\/06\/2024, 09:08 Na noite da \u00faltima segunda-feira (24), o ABC superou o Clube do Remo\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/06\/santana-culpa-apagao-e-consfusao-por-derrota-do-re_00864958_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/06\/santana-culpa-apagao-e-consfusao-por-derrota-do-re_00864958_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/06\/santana-culpa-apagao-e-consfusao-por-derrota-do-re_00864958_0_-3.webp?fit=760%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/06\/santana-culpa-apagao-e-consfusao-por-derrota-do-re_00864958_0_-3.webp?fit=760%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8435,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/com-serie-b-na-porta\/","url_meta":{"origin":6587,"position":4},"title":"COM S\u00c9RIE B NA PORTA","author":"Reda\u00e7\u00e3o","date":"15 de mar\u00e7o de 2025","format":false,"excerpt":"V\u00eddeo: Clube do Remo treina em campo de \"pelada\" e torcida detona Torcida do Remo expressa descontentamento com a falta de estrutura e locais de treinamento \u00e0s v\u00e9speras da S\u00e9rie B. Situa\u00e7\u00e3o gera preocupa\u00e7\u00f5es entre atletas e torcedores. Autor:Lucas Quirino- Fonte:Magno Fernandes\/DOL s\u00e1bado, 15\/03\/2025, 11:28 - Atualizado 15\/03\/2025, 13:43 Em\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-15-at-101930_00898339_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-15-at-101930_00898339_0_-3.webp?fit=760%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-15-at-101930_00898339_0_-3.webp?fit=760%2C430&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-15-at-101930_00898339_0_-3.webp?fit=760%2C430&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10642,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/na-corda-bamba\/","url_meta":{"origin":6587,"position":5},"title":"Remo discute a sa\u00edda do t\u00e9cnico Ant\u00f3nio Oliveira ap\u00f3s empate","author":"Reda\u00e7\u00e3o","date":"17 de agosto de 2025","format":false,"excerpt":"Ant\u00f3nio Oliveira enfrenta press\u00e3o no Clube do Remo ap\u00f3s 10 jogos com 3 vit\u00f3rias. Diretoria avalia futuro do t\u00e9cnico antes de sequ\u00eancia decisiva na S\u00e9rie B. Autor:Kaio Rodrigues\/Dol domingo, 17\/08\/2025, 08:58 A perman\u00eancia do t\u00e9cnico Ant\u00f3nio Oliveira passou a ser discutida internamente ap\u00f3s mais um trope\u00e7o do Clube do Remo\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/08\/Antonio-Oliveira2_00914790_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/08\/Antonio-Oliveira2_00914790_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/08\/Antonio-Oliveira2_00914790_0_-3.webp?fit=760%2C398&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/08\/Antonio-Oliveira2_00914790_0_-3.webp?fit=760%2C398&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peYJxU-1If","_links":{"self":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/comments?post=6587"}],"version-history":[{"count":1,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6587\/revisions"}],"predecessor-version":[{"id":6589,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6587\/revisions\/6589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media\/6588"}],"wp:attachment":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media?parent=6587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/categories?post=6587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/tags?post=6587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}