{"id":6410,"date":"2024-05-17T11:53:02","date_gmt":"2024-05-17T14:53:02","guid":{"rendered":"https:\/\/alvopesquisa.com.br\/blogbelem\/?p=6410"},"modified":"2024-05-17T11:53:02","modified_gmt":"2024-05-17T14:53:02","slug":"veja-quais-estadios-devem-receber-os-jogos-da-copa-feminina-de-2027-no-brasil","status":"publish","type":"post","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/veja-quais-estadios-devem-receber-os-jogos-da-copa-feminina-de-2027-no-brasil\/","title":{"rendered":"Veja quais est\u00e1dios devem receber os jogos da Copa Feminina de 2027 no Brasil"},"content":{"rendered":"<h4>Pa\u00eds ganhou nesta sexta-feira (17) o direito de ser sede da competi\u00e7\u00e3o; proposta enviada pela CBF \u00e0 Fifa tem dez arenas, em dez cidades, incluindo BH, mas isso ainda pode mudar<\/h4>\n<h6><a href=\"https:\/\/www.cnnbrasil.com.br\/autor\/marcel-rizzo\/\">Marcel Rizzo<\/a><span class=\"tp__author\">da<a href=\"https:\/\/www.cnnbrasil.com.br\/esportes\/futebol\/veja-quais-estadios-devem-receber-os-jogos-da-copa-feminina-de-2027-no-brasil\/\"> Itatiaia\/CNN<\/a><\/span><\/h6>\n<p>O Brasil ganhou na madrugada desta sexta-feira (17) o direito de ser sede da Copa do Mundo Feminina de futebol em 2027. Em elei\u00e7\u00e3o durante o Congresso da Fifa, na Tail\u00e2ndia, a candidatura brasileira derrotou a europeia formada por Alemanha, B\u00e9lgica e Holanda. Ser\u00e1 o primeiro mundial feminino na Am\u00e9rica do Sul.<\/p>\n<p>Veja, abaixo, os est\u00e1dios oferecidos pela CBF para a Copa do Mundo Feminina de 2027. No projeto enviado pela CBF (Confedera\u00e7\u00e3o Brasileira de Futebol) \u00e0 Fifa, e usado para avalia\u00e7\u00e3o de especialistas, foram propostos dez est\u00e1dios a receber os jogos, em dez cidades:<\/p>\n<ul>\n<li>Mineir\u00e3o (Belo Horizonte)<\/li>\n<li>Beira-Rio (Porto Alegre)<\/li>\n<li>Man\u00e9 Garrincha (Bras\u00edlia)<\/li>\n<li>Arena Pantanal (Cuiab\u00e1)<\/li>\n<li>Arena da Amaz\u00f4nia (Manaus)<\/li>\n<li>Arena Fonte Nova (Salvador)<\/li>\n<li>Arena de Pernambuco (Recife)<\/li>\n<li>Arena Castel\u00e3o (Fortaleza)<\/li>\n<li>Maracan\u00e3 (Rio)<\/li>\n<li>Neo Qu\u00edmica Arena (S\u00e3o Paulo)<\/li>\n<\/ul>\n<p>Todos foram usados na Copa do Mundo Masculina de 2014 e este foi um dos principais argumentos da candidatura brasileira durante o processo de escolha, o fato de n\u00e3o precisar gastar dinheiro na constru\u00e7\u00e3o de novos equipamentos. Mas a vit\u00f3ria n\u00e3o significa que essas arenas que estavam no projeto ser\u00e3o de fato aquelas usadas no Mundial.<\/p>\n<p>Podem haver mudan\u00e7as nos pr\u00f3ximos meses, a depender de novas vistorias da Fifa. \u00c9, no final das contas, a entidade quem decidir\u00e1. A Arena Pantanal, em Cuiab\u00e1, por exemplo, recebeu nota baixa dos avaliadores. A capital do Mato Grosso tamb\u00e9m foi mal avaliada em quesitos como local para a Fan Fest e acomoda\u00e7\u00f5es, para delega\u00e7\u00f5es e torcedores.<\/p>\n<p>A CBF sugeriu na proposta enviada que a Copa comece em 24 de junho de 2027, uma quinta-feira, com a abertura no Maracan\u00e3, no Rio, em jogo da Sele\u00e7\u00e3o Brasileira pelo Grupo A. A final seria em 25 de julho, no mesmo palco, um domingo. Essas datas tamb\u00e9m s\u00e3o apenas uma sugest\u00e3o neste momento, e podem mudar a depender das necessidades comerciais da Fifa.<\/p>\n<p>A entidade indicou dez est\u00e1dios para receber os jogos da Copa, mas outras dezenas de CTs e est\u00e1dios menores espalhados pelo Brasil para os treinamentos das 31 Sele\u00e7\u00f5es que viajarem ao pa\u00eds para a competi\u00e7\u00e3o. Os 44 CTs ou campos para treinamento foram apontados em 39 cidades diferentes, de 12 estados.<\/p>\n<h2>Veja locais das partidas por dia<\/h2>\n<p><strong>Fase de grupos:<\/strong><\/p>\n<p>24 de junho \u2013 Grupo A \u2013 Est\u00e1dio Maracan\u00e3<br \/>\n25 de junho \u2013 Grupo B \u2013 Est\u00e1dio Mineir\u00e3o e Neo Qu\u00edmica Arena<br \/>\n26 de junho \u2013 Grupos C e D \u2013 Est\u00e1dio Man\u00e9 Garrincha, Arena da Amaz\u00f4nia, Arena Pernambuco e Arena Fonte Nova<br \/>\n27 de junho \u2013 Grupos E e F \u2013 Est\u00e1dios Mineir\u00e3o, Maracan\u00e3 e Beira-Rio<br \/>\n28 de junho \u2013 Grupos F e G \u2013 Neo Qu\u00edmica Arena, Arena Pantanal e Arena da Amaz\u00f4nia<br \/>\n29 de junho \u2013 Grupos A e H \u2013 Arenas Fonte Nova, Pernambuco e Castel\u00e3o<br \/>\n30 de junho \u2013 Grupos A e B \u2013 Est\u00e1dios Man\u00e9 Garrincha, Beira-Rio e Maracan\u00e3<br \/>\n1 de julho \u2013 Grupos C e D \u2013 Arena Pantanal, Arena Pernambuco e Est\u00e1dio Mineir\u00e3o<br \/>\n2 de julho \u2013 Grupos D e E \u2013 Arena Castel\u00e3o, Est\u00e1dio Beira-Rio e Neo Qu\u00edmica Arena<br \/>\n3 de julho \u2013 Grupos F e G \u2013 Est\u00e1dio Maracan\u00e3, Est\u00e1dio Man\u00e9 Garrincha e Arena Fonte Nova<br \/>\n4 de julho \u2013 Grupos G e H \u2013 Est\u00e1dio Mineir\u00e3o, Arena Pantanal e Arena da Amaz\u00f4nia<br \/>\n5 de julho \u2013 Grupos A e B \u2013 Neo Qu\u00edmica Arena, Arena Pernambuco, Est\u00e1dio Beira-Rio e Est\u00e1dio Man\u00e9 Garrincha<br \/>\n6 de julho \u2013 Grupos C e D \u2013 Arenas Castel\u00e3o, Fonte Nova, da Amaz\u00f4nia e Pantanal<br \/>\n7 de julho \u2013 Grupos E e F \u2013 Est\u00e1dios Maracan\u00e3, Man\u00e9 Garrincha, Mineir\u00e3o e Beira-Rio<br \/>\n8 de julho \u2013 Grupos G e H \u2013 Arenas Castel\u00e3o, Pernambuco, Fonte Nova e Neo Qu\u00edmica<\/p>\n<h2>Fase final<\/h2>\n<p><strong>Oitavas<\/strong><\/p>\n<p>10 de julho \u2013 Est\u00e1dios Mineir\u00e3o e Beira-Rio<br \/>\n11 de julho \u2013 Est\u00e1dio Maracan\u00e3 e Arena Pernambuco<br \/>\n12 de julho \u2013 Est\u00e1dio Man\u00e9 Garrincha e Arena Fonte Nova<br \/>\n13 de julho \u2013 Neo Qu\u00edmica Arena e Arena Castel\u00e3o<\/p>\n<p><strong>Quartas<\/strong><\/p>\n<p>16 de julho \u2013 Est\u00e1dio Maracan\u00e3 e Arena Pernambuco<br \/>\n17 de julho \u2013 Est\u00e1dios Mineir\u00e3o e Man\u00e9 Garrincha<\/p>\n<p><strong>Semifinais<\/strong><\/p>\n<p>20 de julho \u2013 Neo Qu\u00edmica Arena<br \/>\n21 de julho \u2013 Est\u00e1dio Man\u00e9 Garrincha<\/p>\n<p><strong>Terceiro lugar<\/strong><\/p>\n<p>24 de julho \u2013 Est\u00e1dio Mineir\u00e3o<\/p>\n<p><strong>Final<\/strong><\/p>\n<p>25 de julho \u2013 Est\u00e1dio Maracan\u00e3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pa\u00eds ganhou nesta sexta-feira (17) o direito de ser sede da competi\u00e7\u00e3o; proposta enviada pela&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[197,327],"tags":[],"class_list":["post-6410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","category-futebol"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=1217%2C663&ssl=1",1217,663,false],"thumbnail":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=300%2C163&ssl=1",300,163,true],"medium_large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=640%2C348&ssl=1",640,348,true],"large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=640%2C349&ssl=1",640,349,true],"1536x1536":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=1217%2C663&ssl=1",1217,663,true],"2048x2048":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=1217%2C663&ssl=1",1217,663,true],"newsever-slider-full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?resize=1217%2C663&ssl=1",1217,663,true],"newsever-featured":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=1024%2C558&ssl=1",1024,558,true],"newsever-medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?resize=720%2C475&ssl=1",720,475,true],"jetpack-portfolio-admin-thumb":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?resize=50%2C50&ssl=1",50,50,true]},"author_info":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/alvopesquisa.com.br\/blogbelem\/author\/socorro-borges\/"},"category_info":"<a href=\"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/\" rel=\"category tag\">ESPORTE<\/a> <a href=\"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/\" rel=\"category tag\">Futebol<\/a>","tag_info":"Futebol","comment_count":"0","jetpack_featured_media_url":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/05\/estadio_maracana-1.jpg?fit=1217%2C663&ssl=1","jetpack-related-posts":[{"id":2185,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/cbf-confirma-que-supercopa-do-brasil-pode-ser-no-mangueirao\/","url_meta":{"origin":6410,"position":0},"title":"CBF confirma que Supercopa do Brasil pode ser no Mangueir\u00e3o","author":"Reda\u00e7\u00e3o","date":"7 de setembro de 2023","format":false,"excerpt":"Presidente Ednaldo Rodrigues, da CBF, gostou das novas instala\u00e7\u00f5es do Ol\u00edmpico do Par\u00e1 e promete mais jogos de grande estrutura; H\u00e1 a possibilidade da Supercopa do Brasil 2024 ser em Bel\u00e9m DOL 06\/09\/2023 Totalmente reformado e no Padr\u00e3o FIFA, o Est\u00e1dio Ol\u00edmpico do Par\u00e1, o Mangueir\u00e3o, entrou, definitivamente, no radar\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-06-at-190931_00826537_0_-3-Presidente-CBF.webp?fit=1199%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-06-at-190931_00826537_0_-3-Presidente-CBF.webp?fit=1199%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-06-at-190931_00826537_0_-3-Presidente-CBF.webp?fit=1199%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-06-at-190931_00826537_0_-3-Presidente-CBF.webp?fit=1199%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-06-at-190931_00826537_0_-3-Presidente-CBF.webp?fit=1199%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11175,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/reencontro-no-caminho\/","url_meta":{"origin":6410,"position":1},"title":"REENCONTRO NO CAMINHO","author":"Reda\u00e7\u00e3o","date":"14 de julho de 2026","format":false,"excerpt":"Mangueir\u00e3o \u00e9 cotado para receber Sele\u00e7\u00e3o em poss\u00edvel despedida de Neymar CBF avalia est\u00e1dios do Norte e Nordeste para a Data Fifa de novembro, e Bel\u00e9m surge como uma das principais candidatas a sediar o \u00faltimo jogo do camisa 10. segunda-feira, 13\/07\/2026, 22:14 -Autor:Magno Fernandes O Est\u00e1dio Ol\u00edmpico do Par\u00e1\u2026","rel":"","context":"Em &quot;ESPORTE&quot;","block_context":{"text":"ESPORTE","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/07\/84b01322d0c0734374c782cfed6241fa.jpg?fit=554%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/07\/84b01322d0c0734374c782cfed6241fa.jpg?fit=554%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/07\/84b01322d0c0734374c782cfed6241fa.jpg?fit=554%2C1200&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1749,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/cbf-anuncia-a-convocacao-para-as-eliminatorias-da-copa-do-mundo-de-2026\/","url_meta":{"origin":6410,"position":2},"title":"CBF anuncia a convoca\u00e7\u00e3o para as eliminat\u00f3rias da copa do mundo de 2026","author":"Jornalista Mayra","date":"18 de agosto de 2023","format":false,"excerpt":"Os convocados v\u00e3o disputar os dois primeiros jogos das eliminat\u00f3rias sul-americanas para a Copa do Mundo Nesta sexta-feira (18), O t\u00e9cnico interino da sele\u00e7\u00e3o brasileira masculina, Fernando Diniz, fez sua primeira convoca\u00e7\u00e3o para a sele\u00e7\u00e3o brasileira, na sede da CBF (Confedera\u00e7\u00e3o Brasileira de Futebol), no Rio de Janeiro. Os jogadores\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/08\/diniz_cbf_widelg.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/08\/diniz_cbf_widelg.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/08\/diniz_cbf_widelg.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/08\/diniz_cbf_widelg.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1296,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/para\/municipios\/cbf-confirma-brasil-x-bolivia-em-belem-pelas-eliminatorias\/","url_meta":{"origin":6410,"position":3},"title":"CBF confirma Brasil x Bol\u00edvia em Bel\u00e9m pelas Eliminat\u00f3rias","author":"Reda\u00e7\u00e3o","date":"31 de julho de 2023","format":false,"excerpt":"Est\u00e1dio do Mangueir\u00e3o, em Bel\u00e9m, cumpriu as exig\u00eancias t\u00e9cnicas e de log\u00edstica para a realiza\u00e7\u00e3o do jogo e volta a receber a Sele\u00e7\u00e3o Canarinho ap\u00f3s 12 anos. segunda-feira, 31\/07\/2023, 21:51 - Atualizado 31\/07\/2023, 21:57 -Autor:Magno Fernandes\/DOL A longa espera do torcedor paraense em poder acompanhar de perto a Sele\u00e7\u00e3o Brasileira,\u2026","rel":"","context":"Em &quot;Munic\u00edpios&quot;","block_context":{"text":"Munic\u00edpios","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/para\/municipios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/Mangueirao.webp?fit=1199%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/Mangueirao.webp?fit=1199%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/Mangueirao.webp?fit=1199%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/Mangueirao.webp?fit=1199%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/Mangueirao.webp?fit=1199%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2133,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/torcida-paraense-aguarda-com-expectativa-jogo-da-selecao-brasileira-no-novo-mangueirao\/","url_meta":{"origin":6410,"position":4},"title":"Torcida paraense aguarda com expectativa jogo da Sele\u00e7\u00e3o Brasileira no Novo Mangueir\u00e3o","author":"Reda\u00e7\u00e3o","date":"4 de setembro de 2023","format":false,"excerpt":"Ap\u00f3s 11 anos, o Par\u00e1 volta a receber o Brasil em data Fifa; partida ser\u00e1 na pr\u00f3xima sexta-feira (8), \u00e0s 21h, no Est\u00e1dio Ol\u00edmpico do Par\u00e1 Jornalista Edgar Proen\u00e7a Por Carol Amorim (SEEL) 04\/09\/2023 O Novo Mangueir\u00e3o ser\u00e1 palco da estreia da Sele\u00e7\u00e3o Brasileira nas eliminat\u00f3rias da Copa do Mundo\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/up_ag_46943_8a090da4-d252-3c89-2efc-40b436610a20-Mangueirao.jpg?fit=800%2C533&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/up_ag_46943_8a090da4-d252-3c89-2efc-40b436610a20-Mangueirao.jpg?fit=800%2C533&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/up_ag_46943_8a090da4-d252-3c89-2efc-40b436610a20-Mangueirao.jpg?fit=800%2C533&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/09\/up_ag_46943_8a090da4-d252-3c89-2efc-40b436610a20-Mangueirao.jpg?fit=800%2C533&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2614,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/nova-casa-do-aguia-de-maraba-esta-quase-pronta\/","url_meta":{"origin":6410,"position":5},"title":"&#8220;Nova casa&#8221; do \u00c1guia de Marab\u00e1 est\u00e1 quase pronta","author":"Reda\u00e7\u00e3o","date":"18 de outubro de 2023","format":false,"excerpt":"Est\u00e1dio Municipal de Marab\u00e1 poder\u00e1 ser o palco do \u00c1guia de Marab\u00e1 na temporada 2024 DOL 18\/10\/2023 Um novo est\u00e1dio de futebol no Par\u00e1 come\u00e7a a sair do papel, animando os torcedores paraenses, em especial do atual campe\u00e3o estadual. As obras no est\u00e1dio municipal de Marab\u00e1 est\u00e3o a todo vapor\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/10\/ESTADIO-MARABAA_00832476_0_-3-4.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/10\/ESTADIO-MARABAA_00832476_0_-3-4.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/10\/ESTADIO-MARABAA_00832476_0_-3-4.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/10\/ESTADIO-MARABAA_00832476_0_-3-4.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/10\/ESTADIO-MARABAA_00832476_0_-3-4.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peYJxU-1Fo","_links":{"self":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/comments?post=6410"}],"version-history":[{"count":3,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6410\/revisions"}],"predecessor-version":[{"id":6415,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/6410\/revisions\/6415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media\/6413"}],"wp:attachment":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media?parent=6410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/categories?post=6410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/tags?post=6410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}