{"id":11086,"date":"2026-05-06T11:02:34","date_gmt":"2026-05-06T14:02:34","guid":{"rendered":"https:\/\/alvopesquisa.com.br\/blogbelem\/?p=11086"},"modified":"2026-05-06T11:02:34","modified_gmt":"2026-05-06T14:02:34","slug":"recuperacao-judicial","status":"publish","type":"post","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/recuperacao-judicial\/","title":{"rendered":"RECUPERA\u00c7\u00c3O JUDICIAL"},"content":{"rendered":"<h1>Paysandu tem d\u00edvida de R$ 71 milh\u00f5es, aponta edital do TJPA<\/h1>\n<h3>Publica\u00e7\u00e3o detalha quem tem valores a receber, abre prazo para manifesta\u00e7\u00f5es e marca nova fase da recupera\u00e7\u00e3o judicial.<\/h3>\n<div class=\"article-info\">\n<h4>quarta-feira, 06\/05\/2026, 07:14<\/h4>\n<h4>&#8211; Atualizado 06\/05\/2026, 08:50<\/h4>\n<p>-Autor:<b><a href=\"https:\/\/dol.com.br\/autor\/14\/lucas-quirino\">Lucas Quirino<\/a><\/b><\/div>\n<div><\/div>\n<div>\n<p>Na \u00faltima ter\u00e7a-feira (5) foi realizada a publica\u00e7\u00e3o do edital de credores da recupera\u00e7\u00e3o judicial do Paysandu Sport Club, jogando luz, de forma detalhada e in\u00e9dita, sobre o tamanho e a composi\u00e7\u00e3o da crise financeira enfrentada pelo clube. Divulgado pela 12\u00aa Vara C\u00edvel e Empresarial de Bel\u00e9m, do Tribunal de Justi\u00e7a do Estado do Par\u00e1, o documento n\u00e3o apenas formaliza uma etapa obrigat\u00f3ria do processo, como tamb\u00e9m delimita quem s\u00e3o os credores, quanto cada um tem a receber e quais ser\u00e3o os pr\u00f3ximos movimentos da reestrutura\u00e7\u00e3o.<\/p>\n<p>Ao todo,\u00a0o edital re\u00fane 123 credores, distribu\u00eddos em diferentes classes, conforme determina a legisla\u00e7\u00e3o. A maior concentra\u00e7\u00e3o est\u00e1 na classe trabalhista, com 102 nomes, refletindo o passivo acumulado com ex-jogadores, funcion\u00e1rios e prestadores de servi\u00e7o. Esses cr\u00e9ditos somam cerca de R$ 2,98 milh\u00f5es, com valores bastante pulverizados, desde pequenas quantias, como R$ 240, at\u00e9 cifras mais robustas ligadas a contratos esportivos.<\/p>\n<p>J\u00e1 entre os credores quirograf\u00e1rios, que n\u00e3o possuem garantia, o cen\u00e1rio \u00e9 bem diferente: s\u00e3o apenas nove credores, mas que concentram R$ 12,86 milh\u00f5es.\u00a0Um \u00fanico credor, o ex-presidente Roger Aguilera, inclusive, responde por mais de R$ 12,3 milh\u00f5es, evidenciando um n\u00edvel elevado de concentra\u00e7\u00e3o que pode ser determinante nas futuras negocia\u00e7\u00f5es. As micro e pequenas empresas aparecem em menor n\u00famero, 12 credores, com aproximadamente R$ 989 mil a receber, representando a cadeia de servi\u00e7os que orbita o clube.<\/p>\n<p>Somadas, as d\u00edvidas sujeitas \u00e0 recupera\u00e7\u00e3o judicial chegam a cerca de R$ 16,8 milh\u00f5es.\u00a0No entanto, o dado que mais chama aten\u00e7\u00e3o est\u00e1 fora desse recorte. O edital tamb\u00e9m exp\u00f5e uma\u00a0d\u00edvida tribut\u00e1ria de aproximadamente R$ 55 milh\u00f5es, vinculada \u00e0 Uni\u00e3o, ao Estado e ao Munic\u00edpio de Bel\u00e9m.\u00a0Por for\u00e7a legal, esses valores n\u00e3o entram na recupera\u00e7\u00e3o judicial, o que imp\u00f5e ao clube a necessidade de buscar solu\u00e7\u00f5es paralelas para regularizar sua situa\u00e7\u00e3o fiscal.<\/p>\n<p>Al\u00e9m de revelar o tamanho do passivo,\u00a0o edital abre oficialmente o prazo de 15 dias para que credores apresentem habilita\u00e7\u00f5es ou contestem os valores listados.\u00a0Esse procedimento deve ser feito diretamente \u00e0 administradora judicial, por meio eletr\u00f4nico, e n\u00e3o por peti\u00e7\u00e3o simples nos autos principais, uma regra que busca evitar o congestionamento do processo. Aqueles que n\u00e3o constam na lista ainda podem se manifestar dentro desse prazo; caso contr\u00e1rio, ter\u00e3o seus pedidos tratados como habilita\u00e7\u00f5es retardat\u00e1rias, em incidentes separados e com poss\u00edvel custo adicional.<\/p>\n<p>A publica\u00e7\u00e3o ocorre no Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico e tamb\u00e9m \u00e9 afixada no F\u00f3rum C\u00edvel de Bel\u00e9m, refor\u00e7ando o car\u00e1ter p\u00fablico e transparente do processo, conforme j\u00e1 havia sido determinado pela Justi\u00e7a ao rejeitar o pedido de sigilo. Na pr\u00e1tica, o edital funciona como um \u201cmapa\u201d das d\u00edvidas do clube e inaugura a fase de verifica\u00e7\u00e3o de cr\u00e9ditos, etapa essencial antes da consolida\u00e7\u00e3o do quadro geral de credores.<\/p>\n<h2>Plano de recupera\u00e7\u00e3o apresentado<\/h2>\n<p>Se o edital organiza o passado financeiro, o plano de recupera\u00e7\u00e3o judicial aponta para o futuro, e revela uma estrat\u00e9gia baseada em cortes expressivos e alongamento das obriga\u00e7\u00f5es.<\/p>\n<p>No documento apresentado \u00e0 Justi\u00e7a, o Paysandu prop\u00f5e condi\u00e7\u00f5es aos seus credores. Para as classes de quirograf\u00e1rios e microempresas, a proposta prev\u00ea um desconto de 85%, ou seja, o pagamento de apenas 15% do valor original das d\u00edvidas. Al\u00e9m disso, o clube solicita uma car\u00eancia de 36 meses antes do in\u00edcio dos pagamentos, seguida de um parcelamento que pode chegar a 120 meses, totalizando at\u00e9 uma d\u00e9cada de quita\u00e7\u00e3o.<\/p>\n<p>No caso dos credores trabalhistas, que t\u00eam prioridade legal, o tratamento \u00e9 diferenciado, mas ainda envolve perdas. O plano prev\u00ea pagamento em at\u00e9 12 meses, por\u00e9m com descontos de 50% sobre os valores devidos. J\u00e1 as verbas salariais mais recentes, limitadas pela legisla\u00e7\u00e3o, devem ser quitadas em prazo mais curto, geralmente em at\u00e9 30 dias ap\u00f3s a homologa\u00e7\u00e3o do plano.<\/p>\n<p>A l\u00f3gica da proposta \u00e9 reduzir significativamente o passivo e ganhar tempo para reorganizar o fluxo de caixa. Para isso, o clube tamb\u00e9m menciona a possibilidade de venda de ativos, renegocia\u00e7\u00e3o de contratos e at\u00e9 mecanismos como da\u00e7\u00e3o em pagamento, buscando alternativas para cumprir as obriga\u00e7\u00f5es dentro de sua capacidade financeira.<\/p>\n<p>O plano, no entanto, ainda depende da aprova\u00e7\u00e3o dos credores, que poder\u00e3o aceitar, rejeitar ou negociar ajustes nas condi\u00e7\u00f5es apresentadas. Diante dos altos descontos e dos prazos extensos, a tend\u00eancia \u00e9 que as discuss\u00f5es sejam intensas, especialmente entre os credores que concentram valores mais elevados.<\/p>\n<p>Com o edital publicado e o plano em an\u00e1lise, a recupera\u00e7\u00e3o judicial entra agora em sua fase mais sens\u00edvel, aquela em que o futuro do clube ser\u00e1 efetivamente decidido na mesa de negocia\u00e7\u00e3o.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Paysandu tem d\u00edvida de R$ 71 milh\u00f5es, aponta edital do TJPA Publica\u00e7\u00e3o detalha quem tem&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[197],"tags":[],"class_list":["post-11086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=760%2C398&ssl=1",760,398,false],"thumbnail":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=640%2C335&ssl=1",640,335,true],"large":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=640%2C335&ssl=1",640,335,true],"1536x1536":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=760%2C398&ssl=1",760,398,true],"2048x2048":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=760%2C398&ssl=1",760,398,true],"newsever-slider-full":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?resize=760%2C398&ssl=1",760,398,true],"newsever-featured":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=760%2C398&ssl=1",760,398,true],"newsever-medium":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?resize=720%2C398&ssl=1",720,398,true],"jetpack-portfolio-admin-thumb":["https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?resize=50%2C50&ssl=1",50,50,true]},"author_info":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/alvopesquisa.com.br\/blogbelem\/author\/socorro-borges\/"},"category_info":"<a href=\"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/\" rel=\"category tag\">ESPORTE<\/a>","tag_info":"ESPORTE","comment_count":"0","jetpack_featured_media_url":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/05\/dscn5628-799x450-2026-05-06-065742009409040-3.webp?fit=760%2C398&ssl=1","jetpack-related-posts":[{"id":11019,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/r-12-milhoes\/","url_meta":{"origin":11086,"position":0},"title":"R$ 12 MILH\u00d5ES","author":"Reda\u00e7\u00e3o","date":"24 de fevereiro de 2026","format":false,"excerpt":"\u201cDoei o dinheiro por amor\u201d, diz Aguilera sobre d\u00edvida com Paysandu Entrevistado na R\u00e1dio Clube do Par\u00e1, o ex-presidente afirmou ter sido surpreendido pela repercuss\u00e3o do caso e negou que esteja cobrando valores do Paysandu Autor:Magno Fernandes\/DOL segunda-feira, 23\/02\/2026, 20:48 Desde o \u00faltimo final de semana, com o Paysandu dando\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/02\/Untitled-3_00935329_0_-3.webp?fit=758%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/02\/Untitled-3_00935329_0_-3.webp?fit=758%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/02\/Untitled-3_00935329_0_-3.webp?fit=758%2C398&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2026\/02\/Untitled-3_00935329_0_-3.webp?fit=758%2C398&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":830,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/paysandu-anuncia-saida-de-vicente-o-21-jogador-a-deixar-o-clube-na-temporada\/","url_meta":{"origin":11086,"position":1},"title":"Paysandu anuncia sa\u00edda de Vicente, o 21\u00b0 jogador a deixar o clube na temporada","author":"Reda\u00e7\u00e3o","date":"28 de junho de 2023","format":false,"excerpt":"Atacante deixa o clube com 14 partidas disputadas e nenhum gol marcado Reda\u00e7\u00e3o do GE \u2014 Bel\u00e9m, PA 27\/06\/2023\u00a0 O Paysandu anunciou a sa\u00edda de Vicente. O atacante \u00e9 o 21\u00b0 jogador a deixar o clube s\u00f3 nesta temporada. Segundo comunicado do clube, a rescis\u00e3o foi em comum acordo. Vicente\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/06\/esporte_3.png?fit=1080%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/06\/esporte_3.png?fit=1080%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/06\/esporte_3.png?fit=1080%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/06\/esporte_3.png?fit=1080%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/06\/esporte_3.png?fit=1080%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":990,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/para\/municipios\/concurso-publico-secretaria-de-saude-do-para-lanca-edital-com-315-vagas-e-salarios-de-ate-r-36-mil\/","url_meta":{"origin":11086,"position":2},"title":"CONCURSO P\u00daBLICO: SECRETARIA DE SA\u00daDE DO PAR\u00c1 LAN\u00c7A EDITAL COM 315 VAGAS E SAL\u00c1RIOS DE AT\u00c9 R$ 3,6 MIL","author":"Reda\u00e7\u00e3o","date":"7 de julho de 2023","format":false,"excerpt":"Provas ser\u00e3o realizadas em setembro em diferentes cidades paraenses. Veja edital e lista de vagas. A Secretaria de Estado da Sa\u00fade (Sespa) lan\u00e7ou nesta sexta-feira (7) edital de concurso p\u00fablico para 315 vagas de n\u00edveis m\u00e9dio e superior, al\u00e9m de cadastro reserva. Os sal\u00e1rios chegam a R$ 3.696,37. As inscri\u00e7\u00f5es\u2026","rel":"","context":"Em &quot;Munic\u00edpios&quot;","block_context":{"text":"Munic\u00edpios","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/para\/municipios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/para_1.jpg?fit=1080%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/para_1.jpg?fit=1080%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/para_1.jpg?fit=1080%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/para_1.jpg?fit=1080%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2023\/07\/para_1.jpg?fit=1080%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10032,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/para\/concurso-tj-pa-tem-banca-definida-saiba-tudo-sobre-edital-vagas-e-salarios\/","url_meta":{"origin":11086,"position":3},"title":"Concurso TJ PA tem banca definida: saiba tudo sobre edital, vagas e sal\u00e1rios","author":"Reda\u00e7\u00e3o","date":"18 de junho de 2025","format":false,"excerpt":"Acordo foi publicado na edi\u00e7\u00e3o desta ter\u00e7a-feira (17) no Di\u00e1rio Oficial do Estado Autor:Tarik Duarte- Fonte:Dire\u00e7\u00e3o Concursos quarta-feira, 18\/06\/2025, 10:08 Quem sonha com uma carreira no servi\u00e7o p\u00fablico muitas vezes busca a estabilidade de uma vaga em tribunais, para garantir bons sal\u00e1rios e um pacote interessante de benef\u00edcios que costuma\u2026","rel":"","context":"Em &quot;PAR\u00c1&quot;","block_context":{"text":"PAR\u00c1","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/para\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/06\/tj_00911469_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/06\/tj_00911469_0_-3.webp?fit=760%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/06\/tj_00911469_0_-3.webp?fit=760%2C398&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/06\/tj_00911469_0_-3.webp?fit=760%2C398&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4816,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol-do-para\/","url_meta":{"origin":11086,"position":4},"title":"Dirigentes de Clube do Remo e Paysandu visitam a CBF","author":"Reda\u00e7\u00e3o","date":"16 de fevereiro de 2024","format":false,"excerpt":"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Ednaldo Rodrigues, recebeu dirigentes de Paysandu e Clube do Remo, na sede da entidade, no Rio de Janeiro. Autor:Diego Beckman, com informa\u00e7\u00f5es da CBF sexta-feira, 16\/02\/2024, 16:18 A for\u00e7a das torcidas e os grandes feitos colocam Paysandu e Clube do Remo como\u2026","rel":"","context":"Em &quot;ESPORTE&quot;","block_context":{"text":"ESPORTE","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/02\/CBFFF_00848320_0_-3.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/02\/CBFFF_00848320_0_-3.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/02\/CBFFF_00848320_0_-3.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/02\/CBFFF_00848320_0_-3.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2024\/02\/CBFFF_00848320_0_-3.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10882,"url":"https:\/\/alvopesquisa.com.br\/blogbelem\/esporte\/futebol\/nova-era-no-papao\/","url_meta":{"origin":11086,"position":5},"title":"Marcelo Sant\u2019Ana chega a Bel\u00e9m e inicia trabalhos no Paysandu","author":"Reda\u00e7\u00e3o","date":"14 de novembro de 2025","format":false,"excerpt":"Marcelo Sant'Ana chega ao Paysandu para reestrutura\u00e7\u00e3o do clube. In\u00edcio do planejamento para 2026 e busca por novo t\u00e9cnico ap\u00f3s rebaixamento. Autor:Magno Fernandes\/Dol quinta-feira, 13\/11\/2025, 22:01 No fim da tarde desta quinta-feira (13), o Paysandu deu mais um passo no processo de reestrutura\u00e7\u00e3o para a temporada de 2026. O novo\u2026","rel":"","context":"Em &quot;Futebol&quot;","block_context":{"text":"Futebol","link":"https:\/\/alvopesquisa.com.br\/blogbelem\/categoria\/esporte\/futebol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/11\/imagem_otimizada-2025-11-13T214245842_00928153_0_.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/11\/imagem_otimizada-2025-11-13T214245842_00928153_0_.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/11\/imagem_otimizada-2025-11-13T214245842_00928153_0_.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/11\/imagem_otimizada-2025-11-13T214245842_00928153_0_.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/alvopesquisa.com.br\/blogbelem\/wp-content\/uploads\/2025\/11\/imagem_otimizada-2025-11-13T214245842_00928153_0_.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peYJxU-2SO","_links":{"self":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/11086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/comments?post=11086"}],"version-history":[{"count":1,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/11086\/revisions"}],"predecessor-version":[{"id":11088,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/posts\/11086\/revisions\/11088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media\/11087"}],"wp:attachment":[{"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/media?parent=11086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/categories?post=11086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alvopesquisa.com.br\/blogbelem\/wp-json\/wp\/v2\/tags?post=11086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}